{"id":3737,"date":"2023-04-25T15:08:43","date_gmt":"2023-04-25T19:08:43","guid":{"rendered":"https:\/\/kurmi.wpengine.com\/socios\/"},"modified":"2025-11-13T10:03:52","modified_gmt":"2025-11-13T15:03:52","slug":"socios","status":"publish","type":"page","link":"https:\/\/kurmi-software.com\/es\/socios\/","title":{"rendered":"Socios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3737\" class=\"elementor elementor-3737 elementor-99\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9eb620 elementor-section-stretched subpage-hero-row orange-row has-img elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9eb620\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-de7ce60\" data-id=\"de7ce60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e69b75c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e69b75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ecosistema de socios de Kurmi<\/h1><p>Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas. Entre nuestros socios se encuentran los principales proveedores de tecnolog\u00eda de comunicaciones unificadas, as\u00ed como integradores de sistemas, distribuidores, revendedores y proveedores de servicios gestionados de primer nivel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ab4df4\" data-id=\"9ab4df4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5edc0ab elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5edc0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"960\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1452684697-900x960.jpg\" class=\"attachment-header-image size-header-image wp-image-3524\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abeb7ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abeb7ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba018ca\" data-id=\"ba018ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6aa48ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6aa48ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38f2c1d\" data-id=\"38f2c1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e81da17 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e81da17\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Socios distribuidores y revendedores<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-daccea1\" data-id=\"daccea1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9096254 card orange-card orange-callout elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9096254\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>As\u00f3ciese con los mejores<\/h2><p>El Programa de Socios de Kurmi ofrece a distribuidores, integradores de sistemas, agentes y revendedores la oportunidad de ofrecer a sus clientes la galardonada soluci\u00f3n de gesti\u00f3n de CU de Kurmi, Flow.<\/p><p>Obtenga nuevos ingresos netos para su empresa al tiempo que a\u00f1ade un valor superior a sus clientes hoy mismo.<\/p><p><a class=\"button\" href=\"https:\/\/kurmi-software.com\/es\/socios\/hagase-socio\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a35306c elementor-section-content-middle elementor-section-stretched burst-top burst-left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a35306c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0aa9d09 elementor-invisible\" data-id=\"0aa9d09\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d4951a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7d4951a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1060\" height=\"1180\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1212010354_Edit-1.jpg\" class=\"attachment-full size-full wp-image-3245\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1212010354_Edit-1.jpg 1060w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1212010354_Edit-1-269x300.jpg 269w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1212010354_Edit-1-920x1024.jpg 920w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1212010354_Edit-1-768x855.jpg 768w\" sizes=\"(max-width: 1060px) 100vw, 1060px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f025bd elementor-invisible\" data-id=\"9f025bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8041cb elementor-widget elementor-widget-image\" data-id=\"b8041cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"88\" height=\"66\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/icon-for-msps-1.svg\" class=\"attachment-full size-full wp-image-2408\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e27ea38 elementor-widget elementor-widget-text-editor\" data-id=\"e27ea38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Proveedores de servicios gestionados (MSP)<\/h2><p>Kurmi Flow es el n\u00facleo de los innovadores servicios de comunicaciones unificadas de los principales proveedores de servicios gestionados de todo el mundo. M\u00e1s informaci\u00f3n sobre la marca blanca de Flow. <\/p><p><a class=\"button\" href=\"https:\/\/kurmi-software.com\/es\/productos\/kurmi-provisioning-suite-para-msp\/\">M\u00e1s informaci\u00f3n<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64e0869 elementor-section-stretched gray-row elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64e0869\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86c8b4f\" data-id=\"86c8b4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-043b21c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"043b21c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Con la confianza de proveedores de servicios de todo el mundo<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-003cdd0 elementor-section-content-middle cards-row elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"003cdd0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-165ffc2 card elementor-invisible\" data-id=\"165ffc2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a996db7 elementor-widget elementor-widget-image\" data-id=\"a996db7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"227\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Verizon_2015_logo_-vector.svg.png\" class=\"attachment-full size-full wp-image-2588\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Verizon_2015_logo_-vector.svg.png 1024w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Verizon_2015_logo_-vector.svg-300x67.png 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Verizon_2015_logo_-vector.svg-768x170.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-fd90f6b card elementor-invisible\" data-id=\"fd90f6b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eb32dd elementor-widget elementor-widget-image\" data-id=\"3eb32dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"491\" height=\"130\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Lumen.png\" class=\"attachment-full size-full wp-image-2570\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Lumen.png 491w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Lumen-300x79.png 300w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c9632c1 card elementor-invisible\" data-id=\"c9632c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce85687 elementor-widget elementor-widget-image\" data-id=\"ce85687\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"78\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/CBTS.png\" class=\"attachment-full size-full wp-image-2573\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c166478 card elementor-invisible\" data-id=\"c166478\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:450}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85fc3d1 elementor-widget elementor-widget-image\" data-id=\"85fc3d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"57\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/NWN.png\" class=\"attachment-full size-full wp-image-2576\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c23cf70 card elementor-invisible\" data-id=\"c23cf70\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bf93f9 elementor-widget elementor-widget-image\" data-id=\"8bf93f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"94\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/CDW.png\" class=\"attachment-full size-full wp-image-2579\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-e8e6e74 card elementor-invisible\" data-id=\"e8e6e74\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:750}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc94b33 elementor-widget elementor-widget-image\" data-id=\"fc94b33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1413\" height=\"743\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/ConvergeOne_Logo.jpg\" class=\"attachment-full size-full wp-image-2582\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/ConvergeOne_Logo.jpg 1413w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/ConvergeOne_Logo-300x158.jpg 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/ConvergeOne_Logo-1024x538.jpg 1024w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/ConvergeOne_Logo-768x404.jpg 768w\" sizes=\"(max-width: 1413px) 100vw, 1413px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a48d585 elementor-section-full_width elementor-section-stretched logo-row elementor-section-height-default elementor-section-height-default\" data-id=\"5a48d585\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7eca53cd\" data-id=\"7eca53cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c318696 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c318696\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-657a6224\" data-id=\"657a6224\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51f216f7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"51f216f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Empresas de 1.000 a m\u00e1s de 100.000 usuarios conf\u00edan en Kurmi Flow para agilizar la gesti\u00f3n de sus CU.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-81c8848 elementor-widget elementor-widget-template\" data-id=\"81c8848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4744\" class=\"elementor elementor-4744 elementor-2225 elementor-2225\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-36a1bf60 elementor-section-content-middle elementor-section-full_width logo-carousel elementor-section-height-default elementor-section-height-default\" data-id=\"36a1bf60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5445ccdc elementor-invisible\" data-id=\"5445ccdc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31cba392 elementor-widget elementor-widget-image\" data-id=\"31cba392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"522\" height=\"96\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/airbus.png\" class=\"attachment-full size-full wp-image-2261\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/airbus.png 522w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/airbus-300x55.png 300w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fbfb4a6 elementor-widget elementor-widget-image\" data-id=\"1fbfb4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-scaled.jpg\" class=\"attachment-full size-full wp-image-2264\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-scaled.jpg 2560w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-300x169.jpg 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-1024x576.jpg 1024w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-768x432.jpg 768w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-1536x864.jpg 1536w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BASF-Logo-2048x1152.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dea5cc elementor-widget elementor-widget-image\" data-id=\"6dea5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"318\" height=\"159\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BNPP.png\" class=\"attachment-full size-full wp-image-2267\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BNPP.png 318w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/BNPP-300x150.png 300w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-225a29e0 elementor-widget elementor-widget-image\" data-id=\"225a29e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"265\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Capital-Group-logo-horizontal.jpg\" class=\"attachment-full size-full wp-image-2270\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Capital-Group-logo-horizontal.jpg 690w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Capital-Group-logo-horizontal-300x115.jpg 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4eaa87 elementor-widget elementor-widget-image\" data-id=\"5c4eaa87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"148\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Duke.png\" class=\"attachment-full size-full wp-image-2276\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Duke.png 340w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Duke-300x131.png 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c554a23 elementor-widget elementor-widget-image\" data-id=\"c554a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"174\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Hermes.png\" class=\"attachment-full size-full wp-image-3530\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207abdc4 elementor-widget elementor-widget-image\" data-id=\"207abdc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"122\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Sub-zero.png\" class=\"attachment-full size-full wp-image-3533\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Sub-zero.png 414w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Sub-zero-300x88.png 300w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b1831b elementor-widget elementor-widget-image\" data-id=\"57b1831b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"107\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Denver-U.png\" class=\"attachment-full size-full wp-image-3539\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Denver-U.png 470w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Denver-U-300x68.png 300w\" sizes=\"(max-width: 470px) 100vw, 470px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5610665c elementor-widget elementor-widget-image\" data-id=\"5610665c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"558\" height=\"90\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Ingram.png\" class=\"attachment-full size-full wp-image-3542\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Ingram.png 558w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Ingram-300x48.png 300w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-288d427 elementor-widget elementor-widget-image\" data-id=\"288d427\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"415\" height=\"121\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Flinders-Univ.png\" class=\"attachment-full size-full wp-image-3569\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Flinders-Univ.png 415w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Flinders-Univ-300x87.png 300w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52d8c07e elementor-widget elementor-widget-image\" data-id=\"52d8c07e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Toronto-police.png\" class=\"attachment-full size-full wp-image-3572\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Toronto-police.png 225w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Toronto-police-150x150.png 150w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Toronto-police-75x75.png 75w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6335a1f4 elementor-widget elementor-widget-image\" data-id=\"6335a1f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"129\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/PWC.png\" class=\"attachment-full size-full wp-image-3575\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/PWC.png 390w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/PWC-300x99.png 300w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ced6b6 elementor-widget elementor-widget-image\" data-id=\"5ced6b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"332\" height=\"152\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Geodis.png\" class=\"attachment-full size-full wp-image-3584\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Geodis.png 332w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/Geodis-300x137.png 300w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe25145 elementor-section-stretched blue-row supported-platforms-row elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe25145\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e60429\" data-id=\"6e60429\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-619885e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"619885e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>M\u00e1s de 20 conectores integrados para los principales proveedores de comunicaciones unificadas y colaboraci\u00f3n.<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cca22f8 platform-logos-col\" data-id=\"cca22f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc4ffe elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5fc4ffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kurmi-software.com\/solutions\/kurmi-for-avaya\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"144\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/avaya.svg\" class=\"attachment-full size-full wp-image-2348\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f635bf elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6f635bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kurmi-software.com\/solutions\/kurmi-for-cisco\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"144\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/cisco.svg\" class=\"attachment-full size-full wp-image-2345\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-935d834 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"935d834\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kurmi-software.com\/solutions\/kurmi-for-microsoft\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"144\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/microsoft.svg\" class=\"attachment-full size-full wp-image-2354\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93fa4ad elementor-invisible elementor-widget elementor-widget-image\" data-id=\"93fa4ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:450}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kurmi-software.com\/solutions\/kurmi-for-zoom\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"144\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/zoom.svg\" class=\"attachment-full size-full wp-image-2351\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d515f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d515f7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dbf8009\" data-id=\"1dbf8009\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-668dea89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"668dea89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-43ec6e48\" data-id=\"43ec6e48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f404e07 elementor-widget elementor-widget-text-editor\" data-id=\"1f404e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Recursos destacados<\/h2><p><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/resources\/\">Todos los recursos<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7fcdf561\" data-id=\"7fcdf561\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fda0af6 elementor-widget elementor-widget-shortcode\" data-id=\"7fda0af6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"resources-container recent-resources\"><div class=\"resources-nav loop-nav\"><\/div><div class=\"resources-wrap\">                <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/05\/Investment-Firm-case-study-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Case Study<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>C\u00f3mo garantiza una empresa de inversi\u00f3n estadounidense la preparaci\u00f3n para <\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/como-garantiza-una-empresa-de-inversion-estadounidense-la-preparacion-para-el-primer-dia-de-150-nuevas-contrataciones-cada-mes\/\">Read More                                        <span class=\"screen-reader-text\"> about C\u00f3mo garantiza una empresa de inversi\u00f3n estadounidense la preparaci\u00f3n para el primer d\u00eda de 150 nuevas contrataciones cada mes<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/04\/Flow-9.1-a-new-ServiceNow-app-get-an-inside-look-at-the-latest--400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/04\/Flow-9.1-a-new-ServiceNow-app-get-an-inside-look-at-the-latest--400x200.png 400w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/04\/Flow-9.1-a-new-ServiceNow-app-get-an-inside-look-at-the-latest--300x150.png 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/04\/Flow-9.1-a-new-ServiceNow-app-get-an-inside-look-at-the-latest-.png 760w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Webinar<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Flow 9.1 + una nueva aplicaci\u00f3n ServiceNow: echa un vistazo a lo \u00faltimo<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" target=\"_blank\" href=\"https:\/\/content.kurmi-software.com\/webinar-flow-9-1\">Watch Now                                        <span class=\"screen-reader-text\"> about Flow 9.1 + una nueva aplicaci\u00f3n ServiceNow: echa un vistazo a lo \u00faltimo<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2026\/03\/Flow-9.1-Release-Blog-Post-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Novedades de Flow 9.1.0: Una experiencia renovada, mayor cobertura y m\u00e1s co<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/novedades-de-flow-9-1-0-una-experiencia-renovada-mayor-cobertura-y-mas-control\/\">Read More                                        <span class=\"screen-reader-text\"> about Novedades de Flow 9.1.0: Una experiencia renovada, mayor cobertura y m\u00e1s control<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2025\/08\/Genesys-Cloud-Connector-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Conector Genesys Cloud de Kurmi Provisioning Suite para unificar los flujos<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/conector-genesys-cloud-de-kurmi-provisioning-suite-para-unificar-los-flujos-de-trabajo-de-contact-center-y-uc\/\">Read More                                        <span class=\"screen-reader-text\"> about Conector Genesys Cloud de Kurmi Provisioning Suite para unificar los flujos de trabajo de Contact Center y UC<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2025\/07\/Kurmi-acquires-Yarnlab-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Press Releases<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Kurmi Software adquiere Yarnlab para ampliar la automatizaci\u00f3n de la migrac<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/kurmi-software-adquiere-yarnlab-para-ampliar-la-automatizacion-de-la-migracion-a-las-comunicaciones-unificadas\/\">Read More                                        <span class=\"screen-reader-text\"> about Kurmi Software adquiere Yarnlab para ampliar la automatizaci\u00f3n de la migraci\u00f3n a las comunicaciones unificadas<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2024\/01\/2023-Roundup-Blog-Post-1-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Kurmi&#8217;s 2023: los productos m\u00e1s destacados<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/kurmi-2023-los-productos-mas-destacados\/\">Read More                                        <span class=\"screen-reader-text\"> about Kurmi&#8217;s 2023: los productos m\u00e1s destacados<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2024\/01\/EM360-Podcast-1-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>\u00bfQu\u00e9 tan cerca est\u00e1 la IA de dirigir todas las comunicaciones empresariales<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/que-tan-cerca-esta-la-ia-de-dirigir-todas-las-comunicaciones-empresariales-un-podcast-de-em360\/\">Read More                                        <span class=\"screen-reader-text\"> about \u00bfQu\u00e9 tan cerca est\u00e1 la IA de dirigir todas las comunicaciones empresariales? &#8211; Un podcast de EM360<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/10\/20230907-Metrigy-Issue-Paper-Hybrid-UC-Management-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">White Paper<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Gesti\u00f3n de las comunicaciones unificadas en la era de lo h\u00edbrido: reducci\u00f3n<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" target=\"_blank\" href=\"https:\/\/content.kurmi-software.com\/metrigy-report-managing-cloud-hybrid-multi-vendor-uc-deployments\">Read More                                        <span class=\"screen-reader-text\"> about Gesti\u00f3n de las comunicaciones unificadas en la era de lo h\u00edbrido: reducci\u00f3n de los costes operativos<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Micah-and-Irwin-3-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Entrevista con Micah Singer en MetriSight<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/entrevista-con-micah-singer-en-metrisight\/\">Read More                                        <span class=\"screen-reader-text\"> about Entrevista con Micah Singer en MetriSight<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/reactivate-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Aspectos destacados del seminario web: Mejores pr\u00e1cticas para gestionar un <\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/aspectos-destacados-del-seminario-web-mejores-practicas-para-gestionar-un-entorno-de-comunicaciones-unificadas-de-varios-proveedores\/\">Read More                                        <span class=\"screen-reader-text\"> about Aspectos destacados del seminario web: Mejores pr\u00e1cticas para gestionar un entorno de comunicaciones unificadas de varios proveedores<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/PartnerIndex_600x338_V3-400x200.jpg\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Conquistando la complejidad &#8211; Una mirada retrospectiva a Cisco Live 2<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/conquistando-la-complejidad-una-mirada-retrospectiva-a-cisco-live-2023\/\">Read More                                        <span class=\"screen-reader-text\"> about Conquistando la complejidad &#8211; Una mirada retrospectiva a Cisco Live 2023<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-400x200.jpg\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-400x200.jpg 400w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-300x150.jpg 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-1024x512.jpg 1024w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-768x384.jpg 768w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-1536x768.jpg 1536w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UCA23_Best-Service-Management-Platform_850x425-2048x1024.jpg 2048w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Press Releases<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Kurmi Software, finalista de los premios UC Today por tercer a\u00f1o consecutiv<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/kurmi-software-finalista-de-los-premios-uc-today-por-tercer-ano-consecutivo\/\">Read More                                        <span class=\"screen-reader-text\"> about Kurmi Software, finalista de los premios UC Today por tercer a\u00f1o consecutivo<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Round-Table-Teams-Compliance-400x200.jpg\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Round-Table-Teams-Compliance-400x200.jpg 400w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Round-Table-Teams-Compliance-300x150.jpg 300w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Round-Table-Teams-Compliance-768x384.jpg 768w, https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/Round-Table-Teams-Compliance.jpg 850w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>UC Today entrevista a Kurmi, Thetalake, Nuwave y Oak Innovation sobre el cu<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/uc-today-entrevista-a-kurmi-thetalake-nuwave-y-oak-innovation-sobre-el-cumplimiento-de-microsoft-teams\/\">Read More                                        <span class=\"screen-reader-text\"> about UC Today entrevista a Kurmi, Thetalake, Nuwave y Oak Innovation sobre el cumplimiento de Microsoft Teams<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n                            <div class=\"resource\">\n                \t<div class=\"wrap\">\n                \t\t<div class=\"featured-image-wrap\">\n\t                \t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/07\/UC-and-UCAAS-for-Hybrid-Work-400x200.png\" class=\"attachment-resource-thumb size-resource-thumb wp-post-image\" alt=\"\" \/>\t                \t<\/div>\n\t                \t<div class=\"resource-info\">\n\t                \t\t<p class=\"resource-tag\">\n\t                \t\t\t<span class=\"tag\">Blog<\/span>\t                \t\t<\/p>\n\t                \t\t<h3>Gestione sus soluciones de comunicaciones unificadas con Kurmi Software &#8<\/h3>\n\t                \t\t                                    <p class=\"more-link\"><a class=\"button ghost-button\" href=\"https:\/\/kurmi-software.com\/es\/resources\/managing-your-uc-solutions-with-kurmi-software-an-interview-with-echannel-news\/\">Read More                                        <span class=\"screen-reader-text\"> about Gestione sus soluciones de comunicaciones unificadas con Kurmi Software &#8211; Entrevista con eChannel News<\/span><\/a><\/p>\n                                \t                \t<\/div>\n\t                <\/div>\n                <\/div>\n            <\/div><\/div>        <script>\n        \tjQuery( document ).ready(function() {\n\t        \tjQuery('.resources-wrap').slick({\n\t        \t\tadaptiveHeight: true,\n\t        \t\tappendArrows: '.resources-nav',\n\t        \t\tslidesToShow: 3,\n\t\t\t\t\tslidesToScroll: 1,\n\t        \t\tarrows: true,\n\t        \t\tprevArrow: '<button type=\"button\" class=\"slider-prev\"><i class=\"fa-solid fa-arrow-left\"><\/i><span class=\"screen-reader-text\">Previous<\/span><\/button>',\n\t        \t\tnextArrow: '<button type=\"button\" class=\"slider-next\"><i class=\"fa-solid fa-arrow-right\"><\/i><span class=\"screen-reader-text\">Next<\/span><\/button>',\n\t        \t\tresponsive: [\n                        {\n                            breakpoint: 961,\n                            settings: {\n                                slidesToShow: 2,\n                            }\n                        },\n                        {\n                            breakpoint: 500,\n                            settings: {\n                                slidesToShow: 1,\n                            }\n                        }\n                    ]\n\t        \t});\n\t        \tjQuery('.resources-wrap').slick('refresh');\n\t        });\n        <\/script>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4825473 elementor-section-stretched dark-blue-row tagline-row elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4825473\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-036cf66\" data-id=\"036cf66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef369d4 elementor-widget elementor-widget-text-editor\" data-id=\"ef369d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Juntos lo configuramos.<\/h2>\n<p style=\"text-align: center;\"><button class=\"demo-opener\">Solicitar una demostraci\u00f3n<\/button><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ecosistema de socios de Kurmi Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas. Entre nuestros socios se encuentran los principales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":440,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"class_list":["post-3737","page","type-page","status-publish","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As\u00f3ciese con Kurmi - Kurmi Software<\/title>\n<meta name=\"description\" content=\"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kurmi-software.com\/es\/socios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00f3ciese con Kurmi - Kurmi Software\" \/>\n<meta property=\"og:description\" content=\"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kurmi-software.com\/es\/socios\/\" \/>\n<meta property=\"og:site_name\" content=\"Kurmi Software\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T15:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/share-img.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kurmisoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/\",\"url\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/\",\"name\":\"As\u00f3ciese con Kurmi - Kurmi Software\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kurmi-software.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/iStock-1452684697-900x960.jpg\",\"datePublished\":\"2023-04-25T19:08:43+00:00\",\"dateModified\":\"2025-11-13T15:03:52+00:00\",\"description\":\"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kurmi-software.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/iStock-1452684697-900x960.jpg\",\"contentUrl\":\"https:\\\/\\\/kurmi-software.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/iStock-1452684697-900x960.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/socios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Socios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/\",\"name\":\"Kurmi Software\",\"description\":\"Unified Communication - Automate &amp; Simplify the management\",\"publisher\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#organization\",\"name\":\"Kurmi Software\",\"url\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kurmi-software.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo.svg\",\"contentUrl\":\"https:\\\/\\\/kurmi-software.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo.svg\",\"width\":200,\"height\":92,\"caption\":\"Kurmi Software\"},\"image\":{\"@id\":\"https:\\\/\\\/kurmi-software.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/kurmisoftware\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kurmi-software\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KurmiSoftware\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00f3ciese con Kurmi - Kurmi Software","description":"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kurmi-software.com\/es\/socios\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00f3ciese con Kurmi - Kurmi Software","og_description":"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.","og_url":"https:\/\/kurmi-software.com\/es\/socios\/","og_site_name":"Kurmi Software","article_modified_time":"2025-11-13T15:03:52+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/share-img.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@kurmisoftware","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kurmi-software.com\/es\/socios\/","url":"https:\/\/kurmi-software.com\/es\/socios\/","name":"As\u00f3ciese con Kurmi - Kurmi Software","isPartOf":{"@id":"https:\/\/kurmi-software.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kurmi-software.com\/es\/socios\/#primaryimage"},"image":{"@id":"https:\/\/kurmi-software.com\/es\/socios\/#primaryimage"},"thumbnailUrl":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1452684697-900x960.jpg","datePublished":"2023-04-25T19:08:43+00:00","dateModified":"2025-11-13T15:03:52+00:00","description":"Los socios de Kurmi conforman un ecosistema global centrado en ofrecer lo mejor en gesti\u00f3n de comunicaciones unificadas.","breadcrumb":{"@id":"https:\/\/kurmi-software.com\/es\/socios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kurmi-software.com\/es\/socios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kurmi-software.com\/es\/socios\/#primaryimage","url":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1452684697-900x960.jpg","contentUrl":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/05\/iStock-1452684697-900x960.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/kurmi-software.com\/es\/socios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kurmi-software.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Socios"}]},{"@type":"WebSite","@id":"https:\/\/kurmi-software.com\/es\/#website","url":"https:\/\/kurmi-software.com\/es\/","name":"Kurmi Software","description":"Unified Communication - Automate &amp; Simplify the management","publisher":{"@id":"https:\/\/kurmi-software.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kurmi-software.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kurmi-software.com\/es\/#organization","name":"Kurmi Software","url":"https:\/\/kurmi-software.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kurmi-software.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Logo.svg","contentUrl":"https:\/\/kurmi-software.com\/wp-content\/uploads\/2023\/04\/Logo.svg","width":200,"height":92,"caption":"Kurmi Software"},"image":{"@id":"https:\/\/kurmi-software.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/kurmisoftware","https:\/\/www.linkedin.com\/company\/kurmi-software\/","https:\/\/www.youtube.com\/user\/KurmiSoftware"]}]}},"_links":{"self":[{"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/pages\/3737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/comments?post=3737"}],"version-history":[{"count":0,"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/pages\/3737\/revisions"}],"wp:attachment":[{"href":"https:\/\/kurmi-software.com\/es\/wp-json\/wp\/v2\/media?parent=3737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}